{"id":17528,"date":"2019-02-07T15:28:55","date_gmt":"2019-02-07T14:28:55","guid":{"rendered":"http:\/\/www.cointecsrl.it\/cms\/?p=17528"},"modified":"2022-12-06T11:40:57","modified_gmt":"2022-12-06T10:40:57","slug":"nuova-normativa-iso-16890","status":"publish","type":"post","link":"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/","title":{"rendered":"Nuova normativa ISO 16890 per la classificazione dei filtri dell&#8217;aria"},"content":{"rendered":"<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Da Giugno 2018 la vecchia normativa europea EN779:2012 sara\u0300 sostituita dal nuovo standard UNI EN ISO 16890 che puntera\u0300 a garantire, per i filtri aria in questione, una maggiore efficienza dei test e una classificazione direttamente collegata alle classi di particolato (PM1 &#8211; PM2,5 &#8211; PM10) andando cosi\u0300 incontro alla sempre piu\u0300 impellente esigenza globale di analisi e miglioramento delle condizioni di qualita\u0300 dell\u2019aria.<\/p>\n<p><strong>Partiamo dalla definizione di PM:<\/strong><br>\nCon la sigla PM vengono individuati gli inquinanti in sospensione nell\u2019aria che possono essere di natura solida, liquida, organica e inorganica.<br>\nIn funzione della dimensione delle particelle che lo compongono i PM si suddividono in:<\/p>\n<ul>\n<li>PM10: particelle con diametro equivalente \u2264 10 \u03bcm<\/li>\n<li>PM2,5: particelle con diametro equivalente \u2264 2,5 \u03bcm<\/li>\n<li>PM1: particelle con diametro equivalente \u2264 1 \u03bcm<\/li>\n<\/ul>\n<p>Nelle immagini possiamo notare alcuni esempi comuni di inquinanti con la dimensione delle particelle che li compongono e l\u2019impatto che queste hanno sul nostro apparato respiratorio.<br>\nLa correlazione tra polveri sottili e alcune patologie quali asme e allergie, tumori e malattie cardiovascolari e\u0300 ormai comprovata da diversi studi.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p><strong><br>\n<img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large wp-image-17531\" src=\"http:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa1-1024x281.jpg\" alt=\"normativa1\" width=\"1024\" height=\"281\" srcset=\"https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa1-1024x281.jpg 1024w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa1-300x82.jpg 300w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa1-768x211.jpg 768w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa1-700x192.jpg 700w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa1.jpg 1893w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/strong><\/p>\n<p><strong> Appurato l\u2019impatto del particolato sulla salute umana, che contributo potra\u0300 dare il nuovo standard UNI EN ISO 16890?<\/strong><br>\n&#8211; Classificazione unica in tutto il mondo (Europa: EN779:2012, America: ASHRAE 52.5, Asia: EN779.2012 + ASHRAE 52.2 + regolamenti locali)<br>\n&#8211; Possibilita\u0300 di dimensionare le sezioni filtranti partendo da dati esistenti o direttamente misurabili localmente per i valori di inquinamento outdoor<br>\n&#8211; Selezione del filtro o delle multiple sezioni filtranti con la corretta efficienza, in modo da immettere in ambiente aria con una concentrazione di contaminante controllata in funzione della qualita\u0300 dell\u2019aria esterna<\/p>\n<p><strong>Perche\u0301 questo non era possibile prima con la vecchia normativa EN779:2012?<\/strong><br>\nLa vecchia normativa europea EN779:2012 presentava alcuni limiti che con l\u2019introduzione della nuova ISO 16890 si andranno a colmare:<br>\n&#8211; Efficienza media misurata in laboratorio piu\u0300 elevata di quella misurata in servizio sia per i media in fibra di vetro che sintetico<br>\n&#8211; Valori di efficienza minimi solo per le classi F7, F8, F9, mentre per i gruppi M e G non ci sono prestazioni minime garantite (vedi tabella)<br>\n&#8211; Quali valori descrivono le prestazioni del filtro? L\u2019efficienza media o minima?<br>\n&#8211; La classificazione si basa esclusivamente su dati raccolti con particelle da 0,4 \u03bcm non tenendo conto delle reali condizioni presenti in atmosfera<br>\n&#8211; La classe dei filtri F viene determinata dalla prova sul materiale e non sul filtro (alcuni materiali immersi in alcool isopropilico vengono alterati, pertanto la corrispondenza non e\u0300 garantita)<\/p>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Classificazione EN779:2012<br>\n<img decoding=\"async\" class=\"alignnone size-full wp-image-17532\" src=\"http:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa2.jpg\" alt=\"normativa2\" width=\"1002\" height=\"488\" srcset=\"https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa2.jpg 1002w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa2-300x146.jpg 300w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa2-768x374.jpg 768w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa2-1000x488.jpg 1000w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa2-700x341.jpg 700w\" sizes=\"(max-width: 1002px) 100vw, 1002px\" \/><\/p>\n<p><strong>UNI EN ISO 16890<\/strong><br>\nLe caratteristiche focali di questo nuovo standard che verra\u0300 introdotto sono:<br>\n&#8211; Utilizzera\u0300 solo l\u2019efficienza iniziale e quella successiva al processo di scarica elettrostatica effettuata sull\u2019intero filtro<br>\n&#8211; L\u2019efficienza sara\u0300 espressa facendo riferimento ad alcune frazioni di massa del pulviscolo atmosferico: PM10, PM2,5 e PM1 e assumera\u0300 la nomenclatura di ePM10 &#8211; ePM2,5 &#8211; ePM1<br>\n&#8211; L\u2019obiettivo sara\u0300 determinare un metodo per poter scegliere i filtri piu\u0300 adeguati mediante \u00abcalcoli\u00bb e formule ben precise<br>\n&#8211; La procedura di carico polvere e\u0300 opzionale e non interferisce con i valori di efficienza<br>\n&#8211; Consentira\u0300 un confronto tra prodotti (EU8, F7, MERV13)<br>\n&#8211; Viene superato il concetto di classe (G3, M6, F8 o F9) in quanto l\u2019efficienza sara\u0300 espressa da una percentuale<br>\n&#8211; Estendera\u0300 l\u2019intervallo di misura fino a 10 \u03bcm per calcolare il valore ePM10 &#8211; Il limite minimo dell\u2019intervallo di misura sara\u0300 pari a 0,3 \u03bcm (la misurazione al di sotto di tale valore e\u0300 costosa ed ininfluente)<br>\n&#8211; Evidenziera\u0300 come la distribuzione e la concentrazione delle particelle sia importante per determinare il valore di ePMx del filtro ed indispensabile per fornire indicazioni relative all\u2019applicazione e non solo al componente.<\/p>\n<p>La nuova ISO 16890 fornira\u0300, a differenza del passato, un approccio\u0300 alla realta\u0300 basato sui modelli di distribuzione delle particelle in atmosfera e andra\u0300 ad esaminare come la concentrazione, cioe\u0300 la massa delle particelle per unita\u0300 di volume d\u2019aria, vari sensibilmente tra il modello urbano e il modello rurale.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-large wp-image-17533\" src=\"http:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa3-1024x425.jpg\" alt=\"normativa3\" width=\"1024\" height=\"425\" srcset=\"https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa3-1024x425.jpg 1024w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa3-300x125.jpg 300w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa3-768x319.jpg 768w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa3-700x291.jpg 700w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa3.jpg 1996w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>La nuova ISO 16890 sviluppera\u0300 i suoi contenuti in 4 parti:<br>\n1. Definizione del sistema di classificazione<br>\n2. Descrizione delle modalita\u0300 per la misurazione dell\u2019efficienza e della perdita di carico in funzione della portata d\u2019aria<br>\n3. Descrizione della misurazione dell\u2019efficienza gravimetrica per filtri con ePM10 \u2264 50%<br>\n4. Descrizione del processo di eliminazione della carica elettrostatica sull\u2019intero filtro<\/p>\n<p>Andiamo a vedere nel dettaglio cosa comprendera\u0300 ognuna delle 4 parti:<\/p>\n<p><strong>1) DEFINIZIZONE DEL SISTEMA DI CLASSIFICAZIONE<\/strong><br>\nIl nuovo standard prevedera\u0300 quattro gruppi:<br>\n&#8211; ISO ePM1<br>\n&#8211; ISO ePM2,5<br>\n&#8211; ISO ePM10<br>\n&#8211; ISO Coarse<\/p>\n<p>Nei primi tre gruppi i filtri verranno classificati in base all\u2019efficienza spettrale, ognuno prendendo in considerazione un certo intervallo dimensionale delle particelle (come si puo\u0300 vedere dalla tabella sottostante), mentre l\u2019ultimo analizzera\u0300 l\u2019arrestanza gravimetrica.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-17534\" src=\"http:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa4-1024x394.jpg\" alt=\"normativa4\" width=\"1024\" height=\"394\" srcset=\"https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa4-1024x394.jpg 1024w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa4-300x115.jpg 300w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa4-768x296.jpg 768w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa4-700x269.jpg 700w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa4.jpg 1029w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Per essere classificati come ePMx nel test dell\u2019efficienza spettrale i filtri dovranno raggiungere un valore maggiore o uguale a 50%, inoltre per le classi ePM1 ed ePM2,5 questa soglia dovra\u0300 essere raggiunta anche nel test in assenza di carica elettrostatica.<br>\nUn filtro e\u0300 facile che potra\u0300 appartenere a piu\u0300 di un gruppo, ma uno solo di essi dovra\u0300 essere riportato insieme alla percentuale di efficienza arrotondata per difetto al 5% piu\u0300 vicino.<\/p>\n<p>Esempio RF92424<br>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-17535\" src=\"http:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa5.jpg\" alt=\"normativa5\" width=\"882\" height=\"148\" srcset=\"https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa5.jpg 882w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa5-300x50.jpg 300w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa5-768x129.jpg 768w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa5-700x117.jpg 700w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/p>\n<p>Per i filtri che non raggiungeranno le condizioni per essere in ePMx sara\u0300 previsto un test di arrestanza gravimetrica con carico polvere ISO Fine e verranno classificati come ISO Coarse a seconda della percentuale di arrestanza.<\/p>\n<p>Esempio S42424406<br>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-17536\" src=\"http:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa6.jpg\" alt=\"normativa6\" width=\"727\" height=\"148\" srcset=\"https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa6.jpg 727w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa6-300x61.jpg 300w, https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa6-700x143.jpg 700w\" sizes=\"(max-width: 727px) 100vw, 727px\" \/><\/p>\n<p><strong>2) DESCRIZIONE DELLE MODALITA\u2019 PER LA MISURAZIONE DELL\u2019EFFICIENZA E DELLA PERDITA DI CARICO IN FUNZIONE DELLA PORTATA D\u2019ARIA<\/strong><br>\nPer quanto riguarda la perdita di carico, il nuovo standard prevedera\u0300 la misurazione della resistenza al flusso d\u2019aria al 50%, 75% 100% e 125% della portata nominale a filtro pulito.<br>\nIl test per l\u2019efficienza frazionale prevedera\u0300 l\u2019uso di due aerosol, ognuno con uno spettro dimensionale di particelle differente e scelti proprio per ragioni fisiche legate alla loro natura. Una volta calcolata la curva di efficienza frazionale il filtro verra\u0300 scaricato elettrostaticamente e verra\u0300 sottoposto allo stesso test svolto in precedenza.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-17537\" src=\"http:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa7-1024x496.jpg\" alt=\"normativa7\" width=\"826\" height=\"359\"><\/p>\n<p>Le due curve ottenute serviranno per calcolare l\u2019ePMx del filtro per poi classificarlo, come descritto nel punto 1, al proprio gruppo di appartenenza.<\/p>\n<p><strong>3) DESCRIZIONE DELLA MISURAZIONE DELL\u2019EFFICIENZA GRAVIMETRICA PER FILTRI CON ePM10 \u2264 50%<\/strong><br>\nSecondo il nuovo standard i test dovranno essere effettuati nello stesso circuito utilizzato precedentemente. Il filtro verra\u0300 pesato e posizionato all\u2019interno del condotto di prova e come prima cosa si determinera\u0300 la resistenza al flusso d\u2019aria. Successivamente si procedera\u0300 al caricamento progressivo della specifica polvere e dopo ogni 30 g di incremento si misureranno i cambiamenti di resistenza al moto. Infine il filtro verra\u0300 pesato nuovamente per determinare la quantita\u0300 di polvere accumulata e calcolare l\u2019efficienza gravimetrica.<\/p>\n<p><strong>4) DESCRIZIONE DEL PROCESSO DI ELIMINAZIONE DELLA CARICA ELETTROSTATICA SULL\u2019INTERO FILTRO<\/strong><br>\nIn questo punto il nuovo standard spieghera\u0300 il processo da effettuare per ottenere il corretto scarico elettrostatico del filtro prima della seconda parte del test per la misurazione dell\u2019efficienza frazionale. Per lo scarico elettrostatico si utilizzera\u0300 del vapore di Isopropanolo, una volta fatto questo si procedera\u0300 al test provando il filtro sia al 100% che al 50% della portata nominale per verificare l\u2019effettiva neutralizzazione delle cariche elettrostatiche e per ottenere il nuovo valore di ePMx.<\/p>\n<p><strong>CONCLUSIONI<\/strong><br>\nIl nuovo standard UNI EN SO 16890 portera\u0300 finalmente una classificazione unica in tutto il mondo con una uniformita\u0300 di linguaggio tecnico in tutte le aree. Il suo altro punto di forza sara\u0300 il dimensionamento dei sistemi filtranti in funzione delle effettive necessita\u0300 di ciascuna applicazione con lo scopo di raggiungere la richiesta concentrazione di particolato indoor cercando di trasmettere un segnale forte per il miglioramento della IAQ.<br>\nI possibili limiti dei questa nuova normativa potranno essere principalmente di natura tecnica legati al fatto che non esiste un legame preciso tra EN779 e ISO 16890 e questo potra\u0300 essere fonte di confusione (andando a perdere i vecchi riferimenti su cui si e\u0300 stati abituati in passato a lavorare). Lo stravolgimento del sistema di test dei filtri richiedera\u0300 da parte dei costruttori un notevole sforzo per adeguarsi ai nuovi standard, questo con il rischio che si continui a scegliere i filtri secondo la vecchia norma sia per comodita\u0300 che alludendo a motivi economici.<br>\nLe opportunita\u0300 per cercare di migliorare il sistema tecnico e operativo sono evidenti, per non parlare della forte spinta che si vuole dare lavorando sul miglioramento della qualita\u0300 dell\u2019aria che respiriamo ogni giorno. Solo il tempo ci potra\u0300 dare indicazioni su come sara\u0300 recepita questo nuovo standard e sugli effettivi benefici che si promette di dare.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n<p>Per maggiori informazioni, clicca <a href=\"https:\/\/www.cointecsrl.it\/cms\/contatti\/\"><strong><span style=\"color:#75ac43\" class=\"has-inline-color\">qui<\/span><\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da Giugno 2018 la vecchia normativa europea EN779:2012 sara\u0300 sostituita dal nuovo standard UNI EN ISO 16890 che puntera\u0300 a garantire, per i filtri aria in questione, una maggiore efficienza dei test e una classificazione direttamente collegata alle classi di particolato (PM1 &#8211; PM2,5 &#8211;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[180],"tags":[],"class_list":["post-17528","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuova normativa ISO 16890 per la classificazione dei filtri dell&#039;aria - Cointec Srl<\/title>\n<meta name=\"description\" content=\"Tutto quello che c&#039;\u00e8 da sapere sulla nuova normativa per la classificazione dei filtri dell&#039;aria UNI EN ISO 16890.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuova normativa ISO 16890 per la classificazione dei filtri dell&#039;aria\" \/>\n<meta property=\"og:description\" content=\"Tutto quello che c&#039;\u00e8 da sapere sulla nuova normativa per la classificazione dei filtri dell&#039;aria UNI EN ISO 16890.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/\" \/>\n<meta property=\"og:site_name\" content=\"Cointec Srl\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-07T14:28:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-06T10:40:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/pexels-rodnae-productions-7821543-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cointec\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cointec\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/\"},\"author\":{\"name\":\"Cointec\",\"@id\":\"https:\/\/www.cointecsrl.it\/cms\/#\/schema\/person\/db2b6ccdd71e399c9f8acf2e79390573\"},\"headline\":\"Nuova normativa ISO 16890 per la classificazione dei filtri dell&#8217;aria\",\"datePublished\":\"2019-02-07T14:28:55+00:00\",\"dateModified\":\"2022-12-06T10:40:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/\"},\"wordCount\":1417,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa1-1024x281.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/\",\"url\":\"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/\",\"name\":\"Nuova normativa ISO 16890 per la classificazione dei filtri dell'aria - Cointec Srl\",\"isPartOf\":{\"@id\":\"https:\/\/www.cointecsrl.it\/cms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa1-1024x281.jpg\",\"datePublished\":\"2019-02-07T14:28:55+00:00\",\"dateModified\":\"2022-12-06T10:40:57+00:00\",\"author\":{\"@id\":\"https:\/\/www.cointecsrl.it\/cms\/#\/schema\/person\/db2b6ccdd71e399c9f8acf2e79390573\"},\"description\":\"Tutto quello che c'\u00e8 da sapere sulla nuova normativa per la classificazione dei filtri dell'aria UNI EN ISO 16890.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/#primaryimage\",\"url\":\"https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa1.jpg\",\"contentUrl\":\"https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa1.jpg\",\"width\":1893,\"height\":520},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cointecsrl.it\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuova normativa ISO 16890 per la classificazione dei filtri dell&#8217;aria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cointecsrl.it\/cms\/#website\",\"url\":\"https:\/\/www.cointecsrl.it\/cms\/\",\"name\":\"Cointec Srl\",\"description\":\"Filtrazione e depurazione dell&#039;aria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cointecsrl.it\/cms\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cointecsrl.it\/cms\/#\/schema\/person\/db2b6ccdd71e399c9f8acf2e79390573\",\"name\":\"Cointec\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.cointecsrl.it\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f359b2e35bf56290301f364dffc6909c1c9a46eebcebd07dcd8edf94d3a79421?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f359b2e35bf56290301f364dffc6909c1c9a46eebcebd07dcd8edf94d3a79421?s=96&d=mm&r=g\",\"caption\":\"Cointec\"},\"url\":\"https:\/\/www.cointecsrl.it\/cms\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuova normativa ISO 16890 per la classificazione dei filtri dell'aria - Cointec Srl","description":"Tutto quello che c'\u00e8 da sapere sulla nuova normativa per la classificazione dei filtri dell'aria UNI EN ISO 16890.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/","og_locale":"it_IT","og_type":"article","og_title":"Nuova normativa ISO 16890 per la classificazione dei filtri dell'aria","og_description":"Tutto quello che c'\u00e8 da sapere sulla nuova normativa per la classificazione dei filtri dell'aria UNI EN ISO 16890.","og_url":"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/","og_site_name":"Cointec Srl","article_published_time":"2019-02-07T14:28:55+00:00","article_modified_time":"2022-12-06T10:40:57+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/pexels-rodnae-productions-7821543-scaled.jpg","type":"image\/jpeg"}],"author":"Cointec","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Cointec","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/#article","isPartOf":{"@id":"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/"},"author":{"name":"Cointec","@id":"https:\/\/www.cointecsrl.it\/cms\/#\/schema\/person\/db2b6ccdd71e399c9f8acf2e79390573"},"headline":"Nuova normativa ISO 16890 per la classificazione dei filtri dell&#8217;aria","datePublished":"2019-02-07T14:28:55+00:00","dateModified":"2022-12-06T10:40:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/"},"wordCount":1417,"commentCount":0,"image":{"@id":"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/#primaryimage"},"thumbnailUrl":"http:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa1-1024x281.jpg","articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/","url":"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/","name":"Nuova normativa ISO 16890 per la classificazione dei filtri dell'aria - Cointec Srl","isPartOf":{"@id":"https:\/\/www.cointecsrl.it\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/#primaryimage"},"image":{"@id":"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/#primaryimage"},"thumbnailUrl":"http:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa1-1024x281.jpg","datePublished":"2019-02-07T14:28:55+00:00","dateModified":"2022-12-06T10:40:57+00:00","author":{"@id":"https:\/\/www.cointecsrl.it\/cms\/#\/schema\/person\/db2b6ccdd71e399c9f8acf2e79390573"},"description":"Tutto quello che c'\u00e8 da sapere sulla nuova normativa per la classificazione dei filtri dell'aria UNI EN ISO 16890.","breadcrumb":{"@id":"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/#primaryimage","url":"https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa1.jpg","contentUrl":"https:\/\/www.cointecsrl.it\/cms\/wp-content\/uploads\/2019\/02\/normativa1.jpg","width":1893,"height":520},{"@type":"BreadcrumbList","@id":"https:\/\/www.cointecsrl.it\/cms\/news\/nuova-normativa-iso-16890\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cointecsrl.it\/cms\/"},{"@type":"ListItem","position":2,"name":"Nuova normativa ISO 16890 per la classificazione dei filtri dell&#8217;aria"}]},{"@type":"WebSite","@id":"https:\/\/www.cointecsrl.it\/cms\/#website","url":"https:\/\/www.cointecsrl.it\/cms\/","name":"Cointec Srl","description":"Filtrazione e depurazione dell&#039;aria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cointecsrl.it\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.cointecsrl.it\/cms\/#\/schema\/person\/db2b6ccdd71e399c9f8acf2e79390573","name":"Cointec","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.cointecsrl.it\/cms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f359b2e35bf56290301f364dffc6909c1c9a46eebcebd07dcd8edf94d3a79421?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f359b2e35bf56290301f364dffc6909c1c9a46eebcebd07dcd8edf94d3a79421?s=96&d=mm&r=g","caption":"Cointec"},"url":"https:\/\/www.cointecsrl.it\/cms\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cointecsrl.it\/cms\/wp-json\/wp\/v2\/posts\/17528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cointecsrl.it\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cointecsrl.it\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cointecsrl.it\/cms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cointecsrl.it\/cms\/wp-json\/wp\/v2\/comments?post=17528"}],"version-history":[{"count":16,"href":"https:\/\/www.cointecsrl.it\/cms\/wp-json\/wp\/v2\/posts\/17528\/revisions"}],"predecessor-version":[{"id":18634,"href":"https:\/\/www.cointecsrl.it\/cms\/wp-json\/wp\/v2\/posts\/17528\/revisions\/18634"}],"wp:attachment":[{"href":"https:\/\/www.cointecsrl.it\/cms\/wp-json\/wp\/v2\/media?parent=17528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cointecsrl.it\/cms\/wp-json\/wp\/v2\/categories?post=17528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cointecsrl.it\/cms\/wp-json\/wp\/v2\/tags?post=17528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}